{"id":132,"date":"2023-09-14T09:21:33","date_gmt":"2023-09-14T08:21:33","guid":{"rendered":"https:\/\/bahamaschinatradeassociation.com\/index.php\/membership-login\/"},"modified":"2023-09-14T09:21:33","modified_gmt":"2023-09-14T08:21:33","slug":"membership-login","status":"publish","type":"page","link":"https:\/\/bahamaschinatradeassociation.com\/index.php\/membership-login\/","title":{"rendered":"\u4f1a\u5458\u767b\u9646"},"content":{"rendered":"<div class=\"swpm-login-widget-form\">\r\n    <form id=\"swpm-login-form\" name=\"swpm-login-form\" method=\"post\" action=\"\">\r\n        <div class=\"swpm-login-form-inner\">\r\n            <div class=\"swpm-username-label\">\r\n                <label for=\"swpm_user_name\" class=\"swpm-label\">Username or Email<\/label>\r\n            <\/div>\r\n            <div class=\"swpm-username-input\">\r\n                <input type=\"text\" class=\"swpm-text-field swpm-username-field\" id=\"swpm_user_name\" value=\"\" size=\"25\" name=\"swpm_user_name\" \/>\r\n            <\/div>\r\n            <div class=\"swpm-password-label\">\r\n                <label for=\"swpm_password\" class=\"swpm-label\">Password<\/label>\r\n            <\/div>\r\n            <div class=\"swpm-password-input\">                \r\n                <input type=\"password\" class=\"swpm-text-field swpm-password-field\" id=\"swpm_password\" value=\"\" size=\"25\" name=\"swpm_password\" \/>                \r\n            <\/div>\r\n                        <div class=\"swpm-remember-me\">\r\n                <span class=\"swpm-remember-checkbox\"><input type=\"checkbox\" name=\"rememberme\" id=\"swpm-rememberme\"><\/span>\r\n                <label for=\"swpm-rememberme\" class=\"swpm-rememberme-label\">\r\n                    <span class=\"swpm-rember-label\"> Remember Me<\/span>\r\n                <\/label>\r\n            <\/div>\r\n\r\n            <div class=\"swpm-before-login-submit-section\"><\/div>\r\n\r\n            <div class=\"swpm-login-submit\">\r\n                <input type=\"submit\" class=\"swpm-login-form-submit\" name=\"swpm-login\" value=\"Log In\"\/>\r\n            <\/div>\r\n            <div class=\"swpm-forgot-pass-link\">\r\n                <a id=\"forgot_pass\" class=\"swpm-login-form-pw-reset-link\"  href=\"https:\/\/bahamaschinatradeassociation.com\/index.php\/membership-login\/password-reset\/\">Forgot Password?<\/a>\r\n            <\/div>\r\n            <div class=\"swpm-join-us-link\">\r\n                <a id=\"register\" class=\"swpm-login-form-register-link\" href=\"https:\/\/bahamaschinatradeassociation.com\/index.php\/membership-join\/\">Join Us<\/a>\r\n            <\/div>\r\n            <div class=\"swpm-login-action-msg\">\r\n                <span class=\"swpm-login-widget-action-msg\"><\/span>\r\n            <\/div>\r\n        <\/div>\r\n    <\/form>\r\n<\/div>\r\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/bahamaschinatradeassociation.com\/index.php\/wp-json\/wp\/v2\/pages\/132"}],"collection":[{"href":"https:\/\/bahamaschinatradeassociation.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bahamaschinatradeassociation.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bahamaschinatradeassociation.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bahamaschinatradeassociation.com\/index.php\/wp-json\/wp\/v2\/comments?post=132"}],"version-history":[{"count":0,"href":"https:\/\/bahamaschinatradeassociation.com\/index.php\/wp-json\/wp\/v2\/pages\/132\/revisions"}],"wp:attachment":[{"href":"https:\/\/bahamaschinatradeassociation.com\/index.php\/wp-json\/wp\/v2\/media?parent=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}